{"id":6901,"date":"2026-04-08T18:25:15","date_gmt":"2026-04-08T18:25:15","guid":{"rendered":"https:\/\/eduardomauricioadvocacia.com\/?p=6901"},"modified":"2026-04-13T18:29:42","modified_gmt":"2026-04-13T18:29:42","slug":"influenciador-passa-de-vitima-de-sequestro-a-investigado-por-desvio-milionario","status":"publish","type":"post","link":"https:\/\/eduardomauricioadvocacia.com\/index.php\/2026\/04\/08\/influenciador-passa-de-vitima-de-sequestro-a-investigado-por-desvio-milionario\/","title":{"rendered":"Influenciador passa de v\u00edtima de sequestro a investigado por desvio milion\u00e1rio"},"content":{"rendered":"\n<iframe title=\"R7 Video Player\" src=\"https:\/\/record.r7.com\/player\/91da70d8-9eb6-4d7f-9d97-e5280086b568\/\" width=\"640\" height=\"360\" frameborder=\"0\" loading=\"lazy\" allowfullscreen><\/iframe>\n\n\n\n<p class=\"wp-block-paragraph\">O influenciador digital e corretor de criptomoedas Gabriel Spalone foi resgatado ap\u00f3s ser sequestrado na zona sul de&nbsp;<a href=\"https:\/\/noticias.r7.com\/sao-paulo\/\"><strong><u>S\u00e3o Paulo<\/u><\/strong><\/a>. Inicialmente tratado como v\u00edtima, ele agora \u00e9 investigado por envolvimento em um esquema milion\u00e1rio que desviou dinheiro de um banco para contas ligadas ao crime organizado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A opera\u00e7\u00e3o come\u00e7ou quando assaltantes tentaram usar o conhecimento t\u00e9cnico do corretor para converter valores roubados em criptomoedas. No entanto, a recusa dele em registrar queixa contra os supostos sequestradores levantou suspeitas sobre seu real papel no crime.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As investiga\u00e7\u00f5es revelam que Gabriel pode ter facilitado a convers\u00e3o ilegal de R$ 146 milh\u00f5es hackeados do banco. O dinheiro foi distribu\u00eddo entre v\u00e1rias contas falsas, e o banco bloqueou uma tentativa de movimenta\u00e7\u00e3o dos fundos devido \u00e0 atividade suspeita.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s o sequestro orquestrado pelos pr\u00f3prios comparsas, cinco pessoas foram presas sob acusa\u00e7\u00f5es relacionadas ao caso. A Pol\u00edcia Civil continua apurando as responsabilidades individuais dentro da quadrilha.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m das pris\u00f5es realizadas, agentes cumpriram mandados que resultaram na apreens\u00e3o de carros de luxo, rel\u00f3gios caros, armas, celulares e computadores usados possivelmente nas transa\u00e7\u00f5es il\u00edcitas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gabriel Spallone responde \u00e0s acusa\u00e7\u00f5es em liberdade enquanto sua defesa argumenta desconhecimento sobre qualquer fraude associada aos valores recebidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: <a href=\"https:\/\/record.r7.com\/fala-brasil\/video\/influenciador-passa-de-vitima-de-sequestro-a-investigado-por-desvio-milionario-08042026\/\">https:\/\/record.r7.com\/fala-brasil\/video\/influenciador-passa-de-vitima-de-sequestro-a-investigado-por-desvio-milionario-08042026\/<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O influenciador digital e corretor de criptomoedas Gabriel Spalone foi resgatado ap\u00f3s ser sequestrado na zona sul de&nbsp;S\u00e3o Paulo. Inicialmente tratado como v\u00edtima, ele agora \u00e9 investigado por envolvimento em um esquema milion\u00e1rio que desviou dinheiro de um banco para contas ligadas ao crime organizado. A opera\u00e7\u00e3o come\u00e7ou quando assaltantes tentaram usar o conhecimento t\u00e9cnico [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6902,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","footnotes":""},"categories":[20],"tags":[168,111,89,165,38,79,72,53,62,58,74],"class_list":["post-6901","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-imprensa","tag-advogado24horas","tag-advogadobrasileiroemportugal","tag-extradicao-2","tag-melhoradvogadoemportugal","tag-advogado-criminalista","tag-destaque_hp","tag-direitopenal","tag-eduardomauricio","tag-extradicao","tag-portugal","tag-sky-ecc"],"_links":{"self":[{"href":"https:\/\/eduardomauricioadvocacia.com\/index.php\/wp-json\/wp\/v2\/posts\/6901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eduardomauricioadvocacia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eduardomauricioadvocacia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eduardomauricioadvocacia.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/eduardomauricioadvocacia.com\/index.php\/wp-json\/wp\/v2\/comments?post=6901"}],"version-history":[{"count":5,"href":"https:\/\/eduardomauricioadvocacia.com\/index.php\/wp-json\/wp\/v2\/posts\/6901\/revisions"}],"predecessor-version":[{"id":6907,"href":"https:\/\/eduardomauricioadvocacia.com\/index.php\/wp-json\/wp\/v2\/posts\/6901\/revisions\/6907"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eduardomauricioadvocacia.com\/index.php\/wp-json\/wp\/v2\/media\/6902"}],"wp:attachment":[{"href":"https:\/\/eduardomauricioadvocacia.com\/index.php\/wp-json\/wp\/v2\/media?parent=6901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eduardomauricioadvocacia.com\/index.php\/wp-json\/wp\/v2\/categories?post=6901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eduardomauricioadvocacia.com\/index.php\/wp-json\/wp\/v2\/tags?post=6901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}